{"id":13824,"date":"2023-07-28T11:31:33","date_gmt":"2023-07-28T09:31:33","guid":{"rendered":"https:\/\/www.lavedetterestaurant.com\/?p=13824"},"modified":"2023-07-30T11:41:10","modified_gmt":"2023-07-30T09:41:10","slug":"galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos","status":"publish","type":"post","link":"https:\/\/www.lavedetterestaurant.com\/fr\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/","title":{"rendered":"Galettes bretonnes avec des ingr\u00e9dients locaux pour tous les go\u00fbts"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">\u00c0 La Vedette, nous offrons une exp\u00e9rience gastronomique bas\u00e9e sur l'utilisation d'ingr\u00e9dients de qualit\u00e9, en privil\u00e9giant les produits locaux et de proximit\u00e9. Nos galettes combinent la <\/span><span class=\"s2\"><b>tradition bretonne<\/b><\/span><span class=\"s1\"> avec les meilleurs <\/span><span class=\"s2\"><b>ingr\u00e9dients locaux<\/b><\/span><span class=\"s1\"> pour cr\u00e9er une grande vari\u00e9t\u00e9 d'options pour tous les palais.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Vous n'avez pas encore go\u00fbt\u00e9 nos galettes ? Laissez-nous vous pr\u00e9senter certaines des options que vous trouverez sur notre menu :<\/span><\/p>\n<p><\/br><\/p>\n<h3 class=\"p1\"><span class=\"s1\"><b>Galettes Classiques<\/b><\/span><\/h3>\n<p class=\"p1\"><span class=\"s1\">Les galettes classiques sont un vrai r\u00e9gal pour les amateurs de <\/span><span class=\"s2\"><b>cuisine traditionnelle<\/b><\/span><span class=\"s1\">. Avec des ingr\u00e9dients typiques comme le fromage ou le jambon sucr\u00e9, nos galettes classiques offrent une combinaison de saveurs authentiques et classiques. Une galette qui se distingue parmi les classiques est :<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u2013 La Compl\u00e8te : Cette galette combine jambon sucr\u00e9, fromage Emmental et \u0153uf, un classique qui remporte toujours un franc succ\u00e8s.<\/span><\/p>\n<p><\/br><\/p>\n<h3 class=\"p1\"><span class=\"s1\"><b>Galettes V\u00e9g\u00e9tariennes et V\u00e9ganes<\/b><\/span><\/h3>\n<p class=\"p1\"><span class=\"s1\">Pour les amateurs de produits frais du jardin, nous proposons une large s\u00e9lection de galettes v\u00e9g\u00e9tariennes et v\u00e9ganes. Ces galettes d\u00e9licieuses et saines se distinguent par leur <\/span><span class=\"s2\"><b>cr\u00e9ativit\u00e9 et leur combinaison d'ingr\u00e9dients<\/b><\/span><span class=\"s1\">. Certaines de nos galettes v\u00e9g\u00e9tariennes sont :<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u2013 La Ruperta : Cette galette pr\u00e9sente une combinaison unique d'\u00e9pinards crus, de parmesan, de confiture de potiron, de graines de potiron et de r\u00e9duction de Mod\u00e8ne, une v\u00e9ritable symphonie de saveurs.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-13826\" src=\"https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2023\/07\/carousel-03-300x146.jpg\" alt=\"\" width=\"1150\" height=\"558\" srcset=\"https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2023\/07\/carousel-03-300x146.jpg 300w, https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2023\/07\/carousel-03-768x373.jpg 768w, https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2023\/07\/carousel-03-18x9.jpg 18w, https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2023\/07\/carousel-03.jpg 869w\" sizes=\"(max-width: 1150px) 100vw, 1150px\" \/><\/p>\n<p class=\"p1\"><span class=\"s1\">\u2013 La Saint-Gilles : Une d\u00e9licieuse galette avec des pommes de terre au four, des courgettes grill\u00e9es, un confit de l\u00e9gumes, de la ciboulette et une cr\u00e8me de fromage Reblochon.<\/span><\/p>\n<p><\/br><\/p>\n<h3 class=\"p1\"><span class=\"s1\"><b>Galettes au Saumon<\/b><\/span><\/h3>\n<p class=\"p1\"><span class=\"s1\">Si vous aimez le poisson, vous devez absolument go\u00fbter nos galettes au saumon. Profitez et explorez deux <\/span><span class=\"s2\"><b>combinaisons de saumon<\/b><\/span><span class=\"s1\"> avec des fromages, des l\u00e9gumes et des \u00e9pices. Un exemple de nos galettes au saumon est :<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u2013\u00a0Palta : Une d\u00e9licieuse galette avec du fromage de ch\u00e8vre, des tomates cerises, de l'avocat, du saumon fum\u00e9 et de la roquette.<\/span><\/p>\n<p><\/br><\/p>\n<h3 class=\"p1\"><span class=\"s1\"><b>Galettes Parisiennes<\/b><\/span><\/h3>\n<p class=\"p1\"><span class=\"s1\">Les galettes parisiennes sont une fusion parfaite de <\/span><span class=\"s2\"><b>saveurs traditionnelles fran\u00e7aises avec une touche contemporaine<\/b><\/span><span class=\"s1\">. Avec des ingr\u00e9dients tels que divers fromages, viandes et charcuteries, diff\u00e9rents l\u00e9gumes et des sauces sp\u00e9ciales, ces cr\u00e9ations vous surprendront. Certaines de nos galettes parisiennes sont :<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u2013 La Vedette : Cette galette associe du fromage de ch\u00e8vre, du magret de canard, du chutney de pomme et une vinaigrette aux fruits rouges pour une explosion de saveurs sophistiqu\u00e9es.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u2013 Saucisse : Une galette irr\u00e9sistible avec de la saucisse grill\u00e9e, du fromage Reblochon, des pommes de terre au four, des oignons confits, de la ciboulette et une vinaigrette \u00e0 la moutarde de Dijon.<\/span><\/p>\n<p><\/br><\/p>\n<h3 class=\"p1\"><span class=\"s1\"><b>Cr\u00eapes Sucr\u00e9es, l'Option Parfaite pour les Desserts<\/b><\/span><\/h3>\n<p class=\"p1\"><span class=\"s1\">\u00c0 La Vedette, nous proposons une grande vari\u00e9t\u00e9 de cr\u00eapes sucr\u00e9es qui combinent des saveurs et des <\/span><span class=\"s2\"><b>ingr\u00e9dients pour tous les go\u00fbts<\/b><\/span><span class=\"s1\">: chocolat, fruits, glace, cr\u00e8me fouett\u00e9e, fruits secs, etc. Voici un petit \u00e9chantillon de nos options pour les amateurs de sucr\u00e9 :<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u2013 Marron : Cette cr\u00eape associe la cr\u00e8me de ch\u00e2taignes \u00e0 une boule de glace \u00e0 la vanille et des noix caram\u00e9lis\u00e9es pour une explosion de saveurs irr\u00e9sistible.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u2013 Atlas : Une cr\u00eape qui vous transportera vers des contr\u00e9es exotiques avec sa combinaison de miel, d'amandes et de glace \u00e0 la vanille.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u2013 Orangette : Cette cr\u00eape offre une combinaison de Grand Marnier, de chocolat chaud et de confiture d'orange.<\/span><\/p>\n<p><\/br><\/p>\n<h5 class=\"p1\"><span class=\"s1\"><b>Profitez de galettes et de cr\u00eapes uniques \u00e9labor\u00e9es avec les meilleurs ingr\u00e9dients locaux<\/b><\/span><\/h5>\n<p class=\"p1\"><span class=\"s1\">Profitez <i>de galettes et de cr\u00eapes uniques \u00e9labor\u00e9es avec les meilleurs ingr\u00e9dients locaux. \u00c0 La Vedette, nous adorons vous voir appr\u00e9cier nos galettes et cr\u00eapes, pr\u00e9par\u00e9es avec des ingr\u00e9dients locaux pour offrir une large gamme d'options pour tous les go\u00fbts<\/i>. De plus, vous pourrez accompagner votre galette ou cr\u00eape de diff\u00e9rentes entr\u00e9es ou d'une irr\u00e9sistible fondue au fromage. Consultez toutes les options que nous vous proposons sur notre carte. Venez nous rendre visite pour profiter d'une exp\u00e9rience gastronomique unique et diff\u00e9rente !<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A La\u00a0Vedette, oferim una experi\u00e8ncia gastron\u00f2mica basada en l&#8217;\u00fas d&#8217;ingredients de qualitat, prioritzant els productes locals i de proximitat. Les nostres\u00a0galettes\u00a0combinen la tradici\u00f3 bretona amb els millors ingredients locals per crear una gran varietat d&#8217;opcions per a tots els paladars. Encara no has tastat les nostres\u00a0galettes? T&#8217;expliquem algunes de les opcions que trobar\u00e0s a la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13825,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Galettes\u00a0bretones amb ingredients locals per a tots els gustos! - La Vedette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lavedetterestaurant.com\/fr\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galettes\u00a0bretones amb ingredients locals per a tots els gustos!\" \/>\n<meta property=\"og:description\" content=\"A La\u00a0Vedette, oferim una experi\u00e8ncia gastron\u00f2mica basada en l&#8217;\u00fas d&#8217;ingredients de qualitat, prioritzant els productes locals i de proximitat. Les nostres\u00a0galettes\u00a0combinen la tradici\u00f3 bretona amb els millors ingredients locals per crear una gran varietat d&#8217;opcions per a tots els paladars. Encara no has tastat les nostres\u00a0galettes? T&#8217;expliquem algunes de les opcions que trobar\u00e0s a la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lavedetterestaurant.com\/fr\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/\" \/>\n<meta property=\"og:site_name\" content=\"La Vedette\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/lavedette00\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-28T09:31:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-30T09:41:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2023\/07\/carousel-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"869\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/#\\\/schema\\\/person\\\/4fba11885565c133d4aaf5b7bfe5d19b\"},\"headline\":\"Galettes\u00a0bretones amb ingredients locals per a tots els gustos!\",\"datePublished\":\"2023-07-28T09:31:33+00:00\",\"dateModified\":\"2023-07-30T09:41:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/\"},\"wordCount\":592,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/carousel-01.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/\",\"url\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/\",\"name\":\"Galettes\u00a0bretones amb ingredients locals per a tots els gustos! - La Vedette\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/carousel-01.jpg\",\"datePublished\":\"2023-07-28T09:31:33+00:00\",\"dateModified\":\"2023-07-30T09:41:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/carousel-01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/carousel-01.jpg\",\"width\":869,\"height\":422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galettes\u00a0bretones amb ingredients locals per a tots els gustos!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/\",\"name\":\"La Vedette\",\"description\":\"Restaurant Cr\u00eaperie Bretonne La Vedette\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/#organization\",\"name\":\"Restaurant Cr\u00eaperie Bretonne La Vedette\",\"url\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/LOGO.png\",\"contentUrl\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/LOGO.png\",\"width\":250,\"height\":158,\"caption\":\"Restaurant Cr\u00eaperie Bretonne La Vedette\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/lavedette00\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/#\\\/schema\\\/person\\\/4fba11885565c133d4aaf5b7bfe5d19b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83e3101f97fc71dc886e0b903e409472d7dca863641d163adef01381593450c8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83e3101f97fc71dc886e0b903e409472d7dca863641d163adef01381593450c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83e3101f97fc71dc886e0b903e409472d7dca863641d163adef01381593450c8?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.lavedetterestaurant.com\"],\"url\":\"https:\\\/\\\/www.lavedetterestaurant.com\\\/fr\\\/author\\\/frame_r3g2tq4d\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Galettes\u00a0bretones amb ingredients locals per a tots els gustos! - La Vedette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lavedetterestaurant.com\/fr\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/","og_locale":"fr_FR","og_type":"article","og_title":"Galettes\u00a0bretones amb ingredients locals per a tots els gustos!","og_description":"A La\u00a0Vedette, oferim una experi\u00e8ncia gastron\u00f2mica basada en l&#8217;\u00fas d&#8217;ingredients de qualitat, prioritzant els productes locals i de proximitat. Les nostres\u00a0galettes\u00a0combinen la tradici\u00f3 bretona amb els millors ingredients locals per crear una gran varietat d&#8217;opcions per a tots els paladars. Encara no has tastat les nostres\u00a0galettes? T&#8217;expliquem algunes de les opcions que trobar\u00e0s a la [&hellip;]","og_url":"https:\/\/www.lavedetterestaurant.com\/fr\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/","og_site_name":"La Vedette","article_publisher":"https:\/\/www.instagram.com\/lavedette00\/","article_published_time":"2023-07-28T09:31:33+00:00","article_modified_time":"2023-07-30T09:41:10+00:00","og_image":[{"width":869,"height":422,"url":"https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2023\/07\/carousel-01.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/#article","isPartOf":{"@id":"https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/"},"author":{"name":"admin","@id":"https:\/\/www.lavedetterestaurant.com\/#\/schema\/person\/4fba11885565c133d4aaf5b7bfe5d19b"},"headline":"Galettes\u00a0bretones amb ingredients locals per a tots els gustos!","datePublished":"2023-07-28T09:31:33+00:00","dateModified":"2023-07-30T09:41:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/"},"wordCount":592,"commentCount":0,"publisher":{"@id":"https:\/\/www.lavedetterestaurant.com\/#organization"},"image":{"@id":"https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2023\/07\/carousel-01.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/","url":"https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/","name":"Galettes\u00a0bretones amb ingredients locals per a tots els gustos! - La Vedette","isPartOf":{"@id":"https:\/\/www.lavedetterestaurant.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/#primaryimage"},"image":{"@id":"https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2023\/07\/carousel-01.jpg","datePublished":"2023-07-28T09:31:33+00:00","dateModified":"2023-07-30T09:41:10+00:00","breadcrumb":{"@id":"https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/#primaryimage","url":"https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2023\/07\/carousel-01.jpg","contentUrl":"https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2023\/07\/carousel-01.jpg","width":869,"height":422},{"@type":"BreadcrumbList","@id":"https:\/\/www.lavedetterestaurant.com\/galettes-bretones-amb-ingredients-locals-per-a-tots-els-gustos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lavedetterestaurant.com\/"},{"@type":"ListItem","position":2,"name":"Galettes\u00a0bretones amb ingredients locals per a tots els gustos!"}]},{"@type":"WebSite","@id":"https:\/\/www.lavedetterestaurant.com\/#website","url":"https:\/\/www.lavedetterestaurant.com\/","name":"The Star","description":"Restaurant Cr\u00eaperie Bretonne La Vedette","publisher":{"@id":"https:\/\/www.lavedetterestaurant.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lavedetterestaurant.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lavedetterestaurant.com\/#organization","name":"Restaurant Cr\u00eaperie Bretonne La Vedette","url":"https:\/\/www.lavedetterestaurant.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lavedetterestaurant.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2022\/01\/LOGO.png","contentUrl":"https:\/\/www.lavedetterestaurant.com\/wp-content\/uploads\/2022\/01\/LOGO.png","width":250,"height":158,"caption":"Restaurant Cr\u00eaperie Bretonne La Vedette"},"image":{"@id":"https:\/\/www.lavedetterestaurant.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/lavedette00\/"]},{"@type":"Person","@id":"https:\/\/www.lavedetterestaurant.com\/#\/schema\/person\/4fba11885565c133d4aaf5b7bfe5d19b","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/83e3101f97fc71dc886e0b903e409472d7dca863641d163adef01381593450c8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83e3101f97fc71dc886e0b903e409472d7dca863641d163adef01381593450c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83e3101f97fc71dc886e0b903e409472d7dca863641d163adef01381593450c8?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.lavedetterestaurant.com"],"url":"https:\/\/www.lavedetterestaurant.com\/fr\/author\/frame_r3g2tq4d\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lavedetterestaurant.com\/fr\/wp-json\/wp\/v2\/posts\/13824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavedetterestaurant.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavedetterestaurant.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavedetterestaurant.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavedetterestaurant.com\/fr\/wp-json\/wp\/v2\/comments?post=13824"}],"version-history":[{"count":5,"href":"https:\/\/www.lavedetterestaurant.com\/fr\/wp-json\/wp\/v2\/posts\/13824\/revisions"}],"predecessor-version":[{"id":13831,"href":"https:\/\/www.lavedetterestaurant.com\/fr\/wp-json\/wp\/v2\/posts\/13824\/revisions\/13831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavedetterestaurant.com\/fr\/wp-json\/wp\/v2\/media\/13825"}],"wp:attachment":[{"href":"https:\/\/www.lavedetterestaurant.com\/fr\/wp-json\/wp\/v2\/media?parent=13824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavedetterestaurant.com\/fr\/wp-json\/wp\/v2\/categories?post=13824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavedetterestaurant.com\/fr\/wp-json\/wp\/v2\/tags?post=13824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}